{"id":5504,"date":"2023-01-16T20:52:48","date_gmt":"2023-01-17T01:52:48","guid":{"rendered":"https:\/\/www.12rbc.ca\/?page_id=5504"},"modified":"2023-01-16T20:52:52","modified_gmt":"2023-01-17T01:52:52","slug":"bottin-du-membership-de-lordre","status":"publish","type":"page","link":"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/","title":{"rendered":"Bottin du membership de l&rsquo;Ordre"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\"><strong>GENRE<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>PR\u00c9NOM<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>NOM<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>TYPE<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>NUM\u00c9RO DU MEMBRE<\/strong><\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Jules<\/td><td class=\"has-text-align-center\" data-align=\"center\">Pinard<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">001<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gilles<\/td><td class=\"has-text-align-center\" data-align=\"center\">S\u00e9guin<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">002<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Roland O<\/td><td class=\"has-text-align-center\" data-align=\"center\">Cyrenne<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">003<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Pierre<\/td><td class=\"has-text-align-center\" data-align=\"center\">Couture<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">004<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Guy<\/td><td class=\"has-text-align-center\" data-align=\"center\">Leblanc<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">005<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Michel<\/td><td class=\"has-text-align-center\" data-align=\"center\">Deveault<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">006<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Jean<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fournier<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">007<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Andr\u00e9<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dumais<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">008<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Mme.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Mich\u00e8le<\/td><td class=\"has-text-align-center\" data-align=\"center\">Allard<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevali\u00e8re<\/td><td class=\"has-text-align-center\" data-align=\"center\">009<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bruno<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bergerons<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">010<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Pierre<\/td><td class=\"has-text-align-center\" data-align=\"center\">C\u00e9cil<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">011<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Yvon<\/td><td class=\"has-text-align-center\" data-align=\"center\">Roberge<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">012<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Claude<\/td><td class=\"has-text-align-center\" data-align=\"center\">Belle-Isle<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">013<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Pierre<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bruneau<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">014<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Richard<\/td><td class=\"has-text-align-center\" data-align=\"center\">Boisclair<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">015<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Michel<\/td><td class=\"has-text-align-center\" data-align=\"center\">Grondin<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">017<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Albert<\/td><td class=\"has-text-align-center\" data-align=\"center\">Geddry<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">018<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Andr\u00e9<\/td><td class=\"has-text-align-center\" data-align=\"center\">Rousseau<\/td><td class=\"has-text-align-center\" data-align=\"center\">Chevalier<\/td><td class=\"has-text-align-center\" data-align=\"center\">019<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n","protected":false},"excerpt":{"rendered":"<p>GENRE PR\u00c9NOM NOM TYPE NUM\u00c9RO DU MEMBRE M. Jules Pinard Chevalier 001 M. Gilles S\u00e9guin Chevalier 002 M. Roland O Cyrenne Chevalier 003 M. Pierre Couture Chevalier 004 M. Guy Leblanc Chevalier 005 M. Michel Deveault Chevalier 006 M. Jean Fournier Chevalier 007 M. Andr\u00e9 Dumais Chevalier 008 Mme. Mich\u00e8le Allard Chevali\u00e8re 009 M. Bruno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-5504","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bottin du membership de l&rsquo;Ordre - Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bottin du membership de l&rsquo;Ordre - Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada\" \/>\n<meta property=\"og:description\" content=\"GENRE PR\u00c9NOM NOM TYPE NUM\u00c9RO DU MEMBRE M. Jules Pinard Chevalier 001 M. Gilles S\u00e9guin Chevalier 002 M. Roland O Cyrenne Chevalier 003 M. Pierre Couture Chevalier 004 M. Guy Leblanc Chevalier 005 M. Michel Deveault Chevalier 006 M. Jean Fournier Chevalier 007 M. Andr\u00e9 Dumais Chevalier 008 Mme. Mich\u00e8le Allard Chevali\u00e8re 009 M. Bruno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/\" \/>\n<meta property=\"og:site_name\" content=\"Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-17T01:52:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/bottin-du-membership-de-lordre\\\/\",\"url\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/bottin-du-membership-de-lordre\\\/\",\"name\":\"Bottin du membership de l&rsquo;Ordre - Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/#website\"},\"datePublished\":\"2023-01-17T01:52:48+00:00\",\"dateModified\":\"2023-01-17T01:52:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/bottin-du-membership-de-lordre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/bottin-du-membership-de-lordre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/bottin-du-membership-de-lordre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bottin du membership de l&rsquo;Ordre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/\",\"name\":\"Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.12rbc.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bottin du membership de l&rsquo;Ordre - Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/","og_locale":"en_US","og_type":"article","og_title":"Bottin du membership de l&rsquo;Ordre - Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada","og_description":"GENRE PR\u00c9NOM NOM TYPE NUM\u00c9RO DU MEMBRE M. Jules Pinard Chevalier 001 M. Gilles S\u00e9guin Chevalier 002 M. Roland O Cyrenne Chevalier 003 M. Pierre Couture Chevalier 004 M. Guy Leblanc Chevalier 005 M. Michel Deveault Chevalier 006 M. Jean Fournier Chevalier 007 M. Andr\u00e9 Dumais Chevalier 008 Mme. Mich\u00e8le Allard Chevali\u00e8re 009 M. Bruno [&hellip;]","og_url":"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/","og_site_name":"Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada","article_modified_time":"2023-01-17T01:52:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/","url":"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/","name":"Bottin du membership de l&rsquo;Ordre - Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada","isPartOf":{"@id":"https:\/\/www.12rbc.ca\/en\/#website"},"datePublished":"2023-01-17T01:52:48+00:00","dateModified":"2023-01-17T01:52:52+00:00","breadcrumb":{"@id":"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.12rbc.ca\/en\/bottin-du-membership-de-lordre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.12rbc.ca\/en\/accueil\/"},{"@type":"ListItem","position":2,"name":"Bottin du membership de l&rsquo;Ordre"}]},{"@type":"WebSite","@id":"https:\/\/www.12rbc.ca\/en\/#website","url":"https:\/\/www.12rbc.ca\/en\/","name":"Association du 12i\u00e8me R\u00e9giment blind\u00e9 du Canada","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.12rbc.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.12rbc.ca\/en\/wp-json\/wp\/v2\/pages\/5504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.12rbc.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.12rbc.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.12rbc.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.12rbc.ca\/en\/wp-json\/wp\/v2\/comments?post=5504"}],"version-history":[{"count":0,"href":"https:\/\/www.12rbc.ca\/en\/wp-json\/wp\/v2\/pages\/5504\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.12rbc.ca\/en\/wp-json\/wp\/v2\/media?parent=5504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}